{"id":425,"date":"2021-08-01T16:59:07","date_gmt":"2021-08-01T16:59:07","guid":{"rendered":"https:\/\/kastenwagenzubehoer.de\/?post_type=product&#038;p=425"},"modified":"2026-01-09T14:53:08","modified_gmt":"2026-01-09T14:53:08","slug":"pc-touch-lamp","status":"publish","type":"product","link":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/","title":{"rendered":"PCS Touch Lamp (Silver)"},"content":{"rendered":"<h2 data-start=\"95\" data-end=\"115\"><span style=\"color: #ffffff;\">Product highlights<\/span><\/h2>\n<ul data-start=\"116\" data-end=\"698\">\n<li data-start=\"116\" data-end=\"190\">\n<p data-start=\"118\" data-end=\"190\">Versatile <strong data-start=\"141\" data-end=\"158\">Recessed light<\/strong> for caravans and indoor areas<\/p>\n<\/li>\n<li data-start=\"191\" data-end=\"292\">\n<p data-start=\"193\" data-end=\"292\">Suitable for: Parquet, wood, laminate and tile floors, conservatories, walls, ceilings and stairs<\/p>\n<\/li>\n<li data-start=\"293\" data-end=\"391\">\n<p data-start=\"295\" data-end=\"391\"><strong data-start=\"295\" data-end=\"316\">Protection class IP67<\/strong>dust and waterproof, therefore almost unlimited application possibilities<\/p>\n<\/li>\n<li data-start=\"392\" data-end=\"480\">\n<p data-start=\"394\" data-end=\"480\"><strong data-start=\"394\" data-end=\"412\">Energy-saving<\/strong> with only 3 W power consumption and input voltage of 10-24 V DC<\/p>\n<\/li>\n<li data-start=\"481\" data-end=\"542\">\n<p data-start=\"483\" data-end=\"542\">LED Technology: Little Heat Development, Long Lifespan<\/p>\n<\/li>\n<li data-start=\"543\" data-end=\"606\">\n<p data-start=\"545\" data-end=\"606\">Warm white light color (3000 K) for a pleasant atmosphere<\/p>\n<\/li>\n<li data-start=\"607\" data-end=\"698\">\n<p data-start=\"609\" data-end=\"698\">Timeless, simple design \u2013 fits unobtrusively and elegantly into any interior<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"700\" data-end=\"703\" \/>\n<h2 data-start=\"705\" data-end=\"727\"><span style=\"color: #ffffff;\">Technical Specifications<\/span><\/h2>\n<ul data-start=\"728\" data-end=\"849\">\n<li data-start=\"728\" data-end=\"760\">\n<p data-start=\"730\" data-end=\"760\">Input voltage: 10-24 V DC<\/p>\n<\/li>\n<li data-start=\"761\" data-end=\"787\">\n<p data-start=\"763\" data-end=\"787\">Power consumption: 3 W<\/p>\n<\/li>\n<li data-start=\"788\" data-end=\"826\">\n<p data-start=\"790\" data-end=\"826\">Light color: 3000 K (warm white)<\/p>\n<\/li>\n<li data-start=\"827\" data-end=\"849\">\n<p data-start=\"829\" data-end=\"849\">Protection class: IP67<\/p>\n<\/li>\n<li data-start=\"827\" data-end=\"849\">Energy efficiency class: A<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Produkthighlights Vielseitig einsetzbare Einbauleuchte f\u00fcr Caravan und Innenbereiche Geeignet f\u00fcr: Parkett-, Holz-, Laminat- und Fliesenb\u00f6den, Winterg\u00e4rten, W\u00e4nde, Decken und Treppen Schutzklasse IP67: staub- und wasserdicht, dadurch nahezu unbegrenzte Einsatzm\u00f6glichkeiten Energiesparend mit nur 3 W Leistungsaufnahme und Eingangsspannung von 10\u201324 V DC LED-Technologie: kaum W\u00e4rmeentwicklung, lange Lebensdauer Warmwei\u00dfe Lichtfarbe (3000 K) f\u00fcr angenehme Atmosph\u00e4re Zeitloses, schlichtes [&hellip;]<\/p>\n","protected":false},"featured_media":8689,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[148],"product_tag":[110],"class_list":["post-425","product","type-product","status-publish","has-post-thumbnail","product_cat-beleuchtung","product_tag-beleuchtung","product_shipping_class-versandkostenpauschale-ii","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato &amp; Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung &amp; mehr!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Kastenwagenzubeh\u00f6r - ausgew\u00e4hlte Produkte f\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\u00f6r\" \/>\n\t\t<meta property=\"og:description\" content=\"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato &amp; Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung &amp; mehr!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-01T16:59:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-09T14:53:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100075609894028\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\u00f6r\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato &amp; Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung &amp; mehr!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt-kategorie\\\/beleuchtung\\\/#listItem\",\"name\":\"Beleuchtung\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt-kategorie\\\/beleuchtung\\\/#listItem\",\"position\":3,\"name\":\"Beleuchtung\",\"item\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt-kategorie\\\/beleuchtung\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#listItem\",\"name\":\"PCS Touch-Lampe (Silber)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#listItem\",\"position\":4,\"name\":\"PCS Touch-Lampe (Silber)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt-kategorie\\\/beleuchtung\\\/#listItem\",\"name\":\"Beleuchtung\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#itempage\",\"url\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/\",\"name\":\"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\\u00f6r\",\"description\":\"Entdecke hochwertiges Wohnmobil - Zubeh\\u00f6r f\\u00fcr Reisemobile, Fiat Ducato & Kastenwagen \\u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung & mehr!\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/PCS-Touch-Lampe-Silber-Schattiert.jpg\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#mainImage\",\"width\":800,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#mainImage\"},\"datePublished\":\"2021-08-01T16:59:07+00:00\",\"dateModified\":\"2026-01-09T14:53:08+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/#organization\",\"name\":\"PCS Promo &amp; Cooler Syndicate GmbH\",\"description\":\"ausgew\\u00e4hlte Produkte f\\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife\",\"url\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/\",\"email\":\"info@pcs-customer-service.com\",\"telephone\":\"+4963449579170\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/PCS-512x512-1.png\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/produkt\\\/pcs-touch-lampe\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100075609894028\",\"https:\\\/\\\/www.instagram.com\\\/kastenwagenzubehoer\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@pcs809\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/\",\"name\":\"Kastenwagenzubeh\\u00f6r\",\"description\":\"ausgew\\u00e4hlte Produkte f\\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/kastenwagenzubehoer.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"PCS Touch Lamp (Silver) - Van Accessories","description":"Discover high-quality camper van accessories for RVs, Fiat Ducato &amp; panel vans \u2013 induction cooktops, lithium batteries, inverters, lighting &amp; more!","canonical_url":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/kastenwagenzubehoer.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/kastenwagenzubehoer.de\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/#listItem","name":"Beleuchtung"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/#listItem","position":3,"name":"Beleuchtung","item":"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#listItem","name":"PCS Touch-Lampe (Silber)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#listItem","position":4,"name":"PCS Touch-Lampe (Silber)","previousItem":{"@type":"ListItem","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/#listItem","name":"Beleuchtung"}}]},{"@type":"ItemPage","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#itempage","url":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/","name":"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\u00f6r","description":"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato & Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung & mehr!","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/kastenwagenzubehoer.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/kastenwagenzubehoer.de\/wp-content\/uploads\/2021\/08\/PCS-Touch-Lampe-Silber-Schattiert.jpg","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#mainImage","width":800,"height":800},"primaryImageOfPage":{"@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#mainImage"},"datePublished":"2021-08-01T16:59:07+00:00","dateModified":"2026-01-09T14:53:08+00:00"},{"@type":"Organization","@id":"https:\/\/kastenwagenzubehoer.de\/en\/#organization","name":"PCS Promo &amp; Cooler Syndicate GmbH","description":"ausgew\u00e4hlte Produkte f\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife","url":"https:\/\/kastenwagenzubehoer.de\/en\/","email":"info@pcs-customer-service.com","telephone":"+4963449579170","logo":{"@type":"ImageObject","url":"https:\/\/kastenwagenzubehoer.de\/wp-content\/uploads\/2024\/11\/PCS-512x512-1.png","@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100075609894028","https:\/\/www.instagram.com\/kastenwagenzubehoer\/","https:\/\/www.youtube.com\/@pcs809"]},{"@type":"WebSite","@id":"https:\/\/kastenwagenzubehoer.de\/en\/#website","url":"https:\/\/kastenwagenzubehoer.de\/en\/","name":"Kastenwagenzubeh\u00f6r","description":"ausgew\u00e4hlte Produkte f\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife","inLanguage":"en-US","publisher":{"@id":"https:\/\/kastenwagenzubehoer.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Kastenwagenzubeh\u00f6r - ausgew\u00e4hlte Produkte f\u00fcr Ihren Kastenwagenausbau | DIY | Vanlife","og:type":"article","og:title":"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\u00f6r","og:description":"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato &amp; Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung &amp; mehr!","og:url":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/","article:published_time":"2021-08-01T16:59:07+00:00","article:modified_time":"2026-01-09T14:53:08+00:00","article:publisher":"https:\/\/www.facebook.com\/profile.php?id=100075609894028","twitter:card":"summary_large_image","twitter:title":"PCS Touch-Lampe (Silber) - Kastenwagenzubeh\u00f6r","twitter:description":"Entdecke hochwertiges Wohnmobil - Zubeh\u00f6r f\u00fcr Reisemobile, Fiat Ducato &amp; Kastenwagen \u2013 Induktionskochfelder, Lithium-Batterien, Wechselrichter, Beleuchtung &amp; mehr!"},"aioseo_meta_data":{"post_id":"425","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-01-13 19:01:13","updated":"2026-01-09 14:55:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kastenwagenzubehoer.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kastenwagenzubehoer.de\/en\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/\" title=\"Beleuchtung\">Beleuchtung<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPCS Touch-Lampe (Silber)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/kastenwagenzubehoer.de\/en"},{"label":"Shop","link":"https:\/\/kastenwagenzubehoer.de\/en\/shop\/"},{"label":"Beleuchtung","link":"https:\/\/kastenwagenzubehoer.de\/en\/produkt-kategorie\/beleuchtung\/"},{"label":"PCS Touch-Lampe (Silber)","link":"https:\/\/kastenwagenzubehoer.de\/en\/produkt\/pcs-touch-lampe\/"}],"_links":{"self":[{"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/product\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/comments?post=425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/media\/8689"}],"wp:attachment":[{"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/product_brand?post=425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/product_cat?post=425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kastenwagenzubehoer.de\/en\/wp-json\/wp\/v2\/product_tag?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}